{"id":4252,"date":"2015-09-21T00:00:00","date_gmt":"2015-09-20T22:00:00","guid":{"rendered":"https:\/\/blog.caritas.barcelona\/acogida-y-acompanamiento\/el-grupo-menarini-presenta-un-concierto-solidario-con-caritas\/"},"modified":"2015-09-21T00:00:00","modified_gmt":"2015-09-20T22:00:00","slug":"el-grupo-menarini-presenta-un-concierto-solidario-con-caritas","status":"publish","type":"post","link":"https:\/\/blog.caritas.barcelona\/es\/entidades-con-corazon\/el-grupo-menarini-presenta-un-concierto-solidario-con-caritas\/","title":{"rendered":"El grupo Menarini presenta un concierto solidario con C\u00e1ritas"},"content":{"rendered":"<p>El pasado 14 de septiembre se present\u00f3, en el Ayuntamiento de Badalona, el <strong>concierto solidario<\/strong> promovido por el\u00a0<strong><a href=\"http:\/\/www.menarini.es\/\" target=\"_blank\">grupo Menarini<\/a><\/strong>, que\u00a0tendr\u00e1 lugar el pr\u00f3ximo 15 de octubre. El dinero recaudado se repartir\u00e1 entre tres entidades, entre ellas <strong>C\u00e1ritas<\/strong>.<!--more--><\/p>\n<p>La rueda de prensa del concierto &#8220;<strong>Gospel &amp; Jazz, notes solid\u00e0ries per Badalona<\/strong>&#8221; tuvo lugar en el Ayuntamiento de Badalona y cont\u00f3 con la presencia de la alcaldesa de la ciudad, la <strong>Sra. M. Dolores Sabater<\/strong>, y con el consejero-general manager de Menarini Espa\u00f1a, el\u00a0<strong>Sr. Salvador Pons<\/strong>.<\/p>\n<p><a href=\"https:\/\/blog.caritas.barcelona\/wp-content\/uploads\/sites\/2\/2015\/09\/IMG_1300.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9109 aligncenter\" alt=\"IMG_1300\" src=\"https:\/\/blog.caritas.barcelona\/wp-content\/uploads\/sites\/2\/2015\/09\/IMG_1300-560x420.jpg\" width=\"560\" height=\"420\" \/><\/a><\/p>\n<p>El concierto tendr\u00e1 lugar el <strong>pr\u00f3ximo 15 de octubre en el Auditori de Barcelona<\/strong>. Estar\u00e1 dirigido por el m\u00fasico y compositor <strong>Erwyn Seerutton<\/strong>, que junto con el <strong>Cor de Gospel Sant Cugat<\/strong> ofrecer\u00e1 al p\u00fablico un espect\u00e1culo musical que integrar\u00e1 dos estilos tan ligados en sus or\u00edgenes como son el gospel y el jazz.<\/p>\n<p>El <strong>dinero recaudado<\/strong> en el concierto ir\u00e1 destinado a <strong>tres entidades<\/strong> que trabajan por el bienestar social de la ciudad: C\u00e1ritas Diocesana de Barcelona, la Fundaci\u00f3 Ateneu Sant Roc y la Fundaci\u00f3 Institut d\u2019Investigaci\u00f3 Germans Trias i Pujol.<\/p>\n<p>Desde C\u00e1ritas queremos agradecer al <strong>grupo Menarini<\/strong> esta iniciativa solidaria, que permitir\u00e1 que podamos seguir trabajando por una sociedad m\u00e1s justa. Tambi\u00e9n agradecemos al <strong>Ayuntamiento de Badalona<\/strong>, al <strong>Auditori de Barcelona<\/strong> y al <strong>Cor de Gospel Sant Cugat<\/strong> su apoyo y disponibilidad a esta propuesta.<\/p>\n<p>Muchas gracias con coraz\u00f3n!!!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 14 de septiembre se present\u00f3, en el Ayuntamiento de Badalona, el concierto solidario promovido por el\u00a0grupo Menarini, que\u00a0tendr\u00e1 lugar el pr\u00f3ximo 15 de octubre. El dinero recaudado se repartir\u00e1 entre tres entidades, entre ellas C\u00e1ritas.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[65,49,880,881,189,190,191,250,846],"autor":[36],"class_list":["post-4252","post","type-post","status-publish","format-standard","hentry","category-entidades-con-corazon","tag-badalona","tag-caritas","tag-concierto","tag-coral","tag-gospel","tag-jazz","tag-menarini","tag-sant-cugat","tag-solidario","autor-caritas-diocesana-de-barcelona-es"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/posts\/4252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/comments?post=4252"}],"version-history":[{"count":0,"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/posts\/4252\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/media?parent=4252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/categories?post=4252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/tags?post=4252"},{"taxonomy":"autor","embeddable":true,"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/autor?post=4252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}