{"id":16224,"date":"2026-04-14T16:42:18","date_gmt":"2026-04-14T14:42:18","guid":{"rendered":"https:\/\/blog.caritas.barcelona\/?p=16224"},"modified":"2026-05-21T15:45:28","modified_gmt":"2026-05-21T13:45:28","slug":"entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social","status":"publish","type":"post","link":"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\/","title":{"rendered":"Entidades de Iglesia consideran la regularizaci\u00f3n extraordinaria de personas  migrantes una medida de responsabilidad pol\u00edtica, \u00e9tica y social"},"content":{"rendered":"<p>Piden a la Administraci\u00f3n que ofrezca posibilidades de registro presencial de expedientes a todas las personas extranjeras potencialmente beneficiarias<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-16219 aligncenter\" src=\"https:\/\/blog.caritas.barcelona\/wp-content\/uploads\/sites\/2\/2026\/04\/Ismael-centroFormacion-4-Caritas-Espanola-scaled-1-1024x768.jpg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blog.caritas.barcelona\/wp-content\/uploads\/sites\/2\/2026\/04\/Ismael-centroFormacion-4-Caritas-Espanola-scaled-1-1024x768.jpg 1024w, https:\/\/blog.caritas.barcelona\/wp-content\/uploads\/sites\/2\/2026\/04\/Ismael-centroFormacion-4-Caritas-Espanola-scaled-1-300x225.jpg 300w, https:\/\/blog.caritas.barcelona\/wp-content\/uploads\/sites\/2\/2026\/04\/Ismael-centroFormacion-4-Caritas-Espanola-scaled-1-768x576.jpg 768w, https:\/\/blog.caritas.barcelona\/wp-content\/uploads\/sites\/2\/2026\/04\/Ismael-centroFormacion-4-Caritas-Espanola-scaled-1-1536x1152.jpg 1536w, https:\/\/blog.caritas.barcelona\/wp-content\/uploads\/sites\/2\/2026\/04\/Ismael-centroFormacion-4-Caritas-Espanola-scaled-1-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>La <strong>Red de Entidades para el Desarrollo Solidario<\/strong> (REDES),\u00a0la <strong>Conferencia Espa\u00f1ola de Religiosos<\/strong> (CONFER),\u00a0<strong>C\u00e1ritas<\/strong>\u00a0y\u00a0el <strong>Departamento de Migraciones de la Conferencia Episcopal Espa\u00f1ola<\/strong>\u00a0consideran que la aprobaci\u00f3n del Real Decreto, que permitir\u00e1 una regularizaci\u00f3n extraordinaria de personas migrantes,\u00a0es una medida de responsabilidad pol\u00edtica, \u00e9tica y social.<\/p>\n<p>Ante un proceso tan complejo t\u00e9cnica y log\u00edsticamente que ha de desarrollarse en un per\u00edodo muy limitado de tiempo, <strong>las entidades firmantes conf\u00edan en que el proceso de regularizaci\u00f3n extraordinaria d\u00e9 respuesta a todas las personas que se encuentran en situaci\u00f3n administrativa irregular<\/strong>, en particular aquellas que llevan sufriendo estas circunstancias durante un largo per\u00edodo de tiempo y no logran regularizar su situaci\u00f3n por las v\u00edas ordinarias de la normativa de extranjer\u00eda.<\/p>\n<p>Este objetivo \u00fanicamente ser\u00e1 posible si la Administraci\u00f3n se dota de los<strong> medios adecuados para ofrecer informaci\u00f3n de calidad y ofrece posibilidades de registro presencial de expedientes a todas las personas extranjeras potencialmente beneficiarias.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-16082 aligncenter\" src=\"https:\/\/blog.caritas.barcelona\/wp-content\/uploads\/sites\/2\/2026\/02\/20200217_INFORME_MIGRACIO_@MINGO_VENERO-26-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" \/><\/p>\n<h3><strong>Expresi\u00f3n coherente del Evangelio<\/strong><\/h3>\n<p><strong>La acogida, la protecci\u00f3n y la dignificaci\u00f3n de las personas migrantes constituyen para la Iglesia una exigencia inherente a su misi\u00f3n<\/strong>. No se trata \u00fanicamente de una opci\u00f3n pastoral, sino tambi\u00e9n una exigencia en materia de derechos humanos y por tanto de una expresi\u00f3n coherente del Evangelio en la vida p\u00fablica.<\/p>\n<p>Este paso decidido hacia una sociedad m\u00e1s justa e inclusiva, donde nadie quede relegado a la invisibilidad y la exclusi\u00f3n,\u00a0<strong>supone adem\u00e1s\u00a0un refrendo al\u00a0proceso participativo\u00a0impulsado por\u00a0la sociedad civil, que\u00a0logr\u00f3 concitar\u00a0a m\u00e1s de 900 organizaciones de toda \u00edndole\u00a0y\u00a0recabar m\u00e1s de 600.000 firmas para la tramitaci\u00f3n de la Iniciativa Legislativa Popular (ILP).\u00a0<\/strong><\/p>\n<p>Desde el a\u00f1o 2023 las cuatro entidades\u00a0eclesiales\u00a0han participado\u00a0en este proceso y\u00a0en multitud de reuniones con actores pol\u00edticos y sociales exponiendo la preocupaci\u00f3n compartida y constatada en el d\u00eda a d\u00eda de\u00a0su\u00a0labor de acompa\u00f1amiento por la relaci\u00f3n innegable entre irregularidad administrativa y exclusi\u00f3n social.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-15905 aligncenter\" src=\"https:\/\/blog.caritas.barcelona\/wp-content\/uploads\/sites\/2\/2026\/01\/83850b12-5ad5-4b0d-9388-e033dc7e5d84-1024x682.jpg\" alt=\"\" width=\"1024\" height=\"682\" \/><\/p>\n<p>La irregularidad administrativa coloca a las personas que residen en Espa\u00f1a en una situaci\u00f3n de fuerte vulnerabilidad, ya que limita gravemente su acceso a derechos b\u00e1sicos y las expone a m\u00faltiples formas de discriminaci\u00f3n.\u00a0Seg\u00fan el<strong>\u00a0<a href=\"https:\/\/bit.ly\/4oaKUGM\" target=\"_blank\" rel=\"noopener\">IX Informe FOESSA sobre exclusi\u00f3n y desarrollo social<\/a><\/strong>,\u00a0<strong>casi nueve millones\u00a0de personas migrantes\u00a0viven en nuestro pa\u00eds. La situaci\u00f3n administrativa irregular en la que est\u00e1n muchas de ellas provoca que el 68% se encuentre en exclusi\u00f3n social.\u00a0\u00a0<\/strong><\/p>\n<p>Seg\u00fan los \u00faltimos datos\u00a0publicados por C\u00e1ritas, el 47% de las personas acompa\u00f1adas por la instituci\u00f3n en 2024 no ten\u00eda regularizada su situaci\u00f3n, lo que equivale aproximadamente a unas 550.000 personas. Una cifra que no para de crecer desde 2019.\u00a0Al final, la irregularidad no solo limita la autonom\u00eda personal, sino que genera un c\u00edrculo de invisibilidad y desprotecci\u00f3n que afecta a toda la convivencia social.<\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-16080 aligncenter\" src=\"https:\/\/blog.caritas.barcelona\/wp-content\/uploads\/sites\/2\/2026\/02\/20200217_INFORME_MIGRACIO_@MINGO_VENERO-23-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" \/><\/h3>\n<h3><strong>Salir de la incertidumbre y la vulnerabilidad<\/strong><\/h3>\n<p>La regularizaci\u00f3n administrativa transforma de manera profunda la vida de las personas migrantes, porque les <strong>permite salir de la incertidumbre y la vulnerabilidad asociadas a la irregularidad y acceder plenamente a derechos y oportunidades b\u00e1sicas<\/strong>. Contar con una autorizaci\u00f3n de residencia y trabajo abre la puerta al empleo formal y digno, a la estabilidad econ\u00f3mica y a la posibilidad de planificar un proyecto de vida.<\/p>\n<p>Tambi\u00e9n<strong> facilita el acceso efectivo a la sanidad, la vivienda, la educaci\u00f3n y otros servicios esenciales, adem\u00e1s de permitir realizar tr\u00e1mites cotidianos<\/strong> \u2014como abrir una cuenta bancaria o firmar un contrato\u2014 sin miedo. La regularizaci\u00f3n reduce la exposici\u00f3n a la explotaci\u00f3n laboral, a la discriminaci\u00f3n y a situaciones de abuso, y ofrece la tranquilidad de poder circular y relacionarse con las instituciones sin riesgo. En definitiva, supone pasar de la invisibilidad y la precariedad a la protecci\u00f3n, la autonom\u00eda y la plena participaci\u00f3n social.<\/p>\n<p><strong>La regularizaci\u00f3n permitir\u00e1 que cientos de miles de personas coticen, paguen impuestos y contribuyan formalmente al sostenimiento de los servicios p\u00fablicos, reforzando el Estado del bienestar.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Piden a la Administraci\u00f3n que ofrezca posibilidades de registro presencial de expedientes a todas las personas extranjeras potencialmente beneficiarias La Red de Entidades para el Desarrollo Solidario (REDES),\u00a0la Conferencia Espa\u00f1ola de Religiosos (CONFER),\u00a0C\u00e1ritas\u00a0y\u00a0el Departamento de Migraciones de la Conferencia Episcopal Espa\u00f1ola\u00a0consideran que la aprobaci\u00f3n del Real Decreto, que permitir\u00e1 una regularizaci\u00f3n extraordinaria de personas migrantes,\u00a0es [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":16220,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"autor":[36],"class_list":["post-16224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilidad-humana","autor-caritas-diocesana-de-barcelona-es"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Piden a la Administraci\u00f3n que ofrezca posibilidades de registro presencial de expedientes a todas las personas extranjeras potencialmente beneficiarias La Red de Entidades para el Desarrollo Solidario (REDES), la Conferencia Espa\u00f1ola de Religiosos (CONFER), C\u00e1ritas y el Departamento de Migraciones de la Conferencia Episcopal Espa\u00f1ola consideran que la aprobaci\u00f3n del Real Decreto, que permitir\u00e1 una regularizaci\u00f3n extraordinaria de personas migrantes, es\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"C\u00e0ritas Diocesana de Barcelona\"\/>\n\t<meta name=\"keywords\" content=\"mobilidad humana\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Blog de C\u00e1ritas Barcelona\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Entidades de Iglesia consideran la regularizaci\u00f3n extraordinaria de personas migrantes una medida de responsabilidad pol\u00edtica, \u00e9tica y social | Blog de C\u00e1ritas Barcelona\" \/>\n\t\t<meta property=\"og:description\" content=\"Piden a la Administraci\u00f3n que ofrezca posibilidades de registro presencial de expedientes a todas las personas extranjeras potencialmente beneficiarias La Red de Entidades para el Desarrollo Solidario (REDES), la Conferencia Espa\u00f1ola de Religiosos (CONFER), C\u00e1ritas y el Departamento de Migraciones de la Conferencia Episcopal Espa\u00f1ola consideran que la aprobaci\u00f3n del Real Decreto, que permitir\u00e1 una regularizaci\u00f3n extraordinaria de personas migrantes, es\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\/\" \/>\n\t\t<meta property=\"fb:admins\" content=\"100006058908787\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/blog.caritas.barcelona\/wp-content\/uploads\/sites\/2\/2026\/04\/Ismael-centroFormacion-4-Caritas-Espanola-scaled-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/blog.caritas.barcelona\/wp-content\/uploads\/sites\/2\/2026\/04\/Ismael-centroFormacion-4-Caritas-Espanola-scaled-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t\t<meta property=\"article:tag\" content=\"mobilidad humana\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-04-14T14:42:18+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-05-21T13:45:28+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/caritasbarcelona\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@caritasbcn\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Entidades de Iglesia consideran la regularizaci\u00f3n extraordinaria de personas migrantes una medida de responsabilidad pol\u00edtica, \u00e9tica y social | Blog de C\u00e1ritas Barcelona\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Piden a la Administraci\u00f3n que ofrezca posibilidades de registro presencial de expedientes a todas las personas extranjeras potencialmente beneficiarias La Red de Entidades para el Desarrollo Solidario (REDES), la Conferencia Espa\u00f1ola de Religiosos (CONFER), C\u00e1ritas y el Departamento de Migraciones de la Conferencia Episcopal Espa\u00f1ola consideran que la aprobaci\u00f3n del Real Decreto, que permitir\u00e1 una regularizaci\u00f3n extraordinaria de personas migrantes, es\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@caritasbcn\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/blog.caritas.barcelona\/wp-content\/uploads\/sites\/2\/2026\/04\/Ismael-centroFormacion-4-Caritas-Espanola-scaled-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/mobilidad-humana\\\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\\\/#blogposting\",\"name\":\"Entidades de Iglesia consideran la regularizaci\\u00f3n extraordinaria de personas migrantes una medida de responsabilidad pol\\u00edtica, \\u00e9tica y social | Blog de C\\u00e1ritas Barcelona\",\"headline\":\"Entidades de Iglesia consideran la regularizaci\\u00f3n extraordinaria de personas  migrantes una medida de responsabilidad pol\\u00edtica, \\u00e9tica y social\",\"author\":{\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/author\\\/gestorwebcaritas17\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.caritas.barcelona\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/04\\\/Ismael-centroFormacion-4-Caritas-Espanola-scaled-1.jpg\",\"width\":2560,\"height\":1920},\"datePublished\":\"2026-04-14T16:42:18+02:00\",\"dateModified\":\"2026-05-21T15:45:28+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/mobilidad-humana\\\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/mobilidad-humana\\\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\\\/#webpage\"},\"articleSection\":\"Mobilidad Humana, Opcional, C\\u00e1ritas Diocesana de Barcelona\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/mobilidad-humana\\\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/mobilidad-humana\\\/#listItem\",\"name\":\"Mobilidad Humana\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/mobilidad-humana\\\/#listItem\",\"position\":2,\"name\":\"Mobilidad Humana\",\"item\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/mobilidad-humana\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/mobilidad-humana\\\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\\\/#listItem\",\"name\":\"Entidades de Iglesia consideran la regularizaci\\u00f3n extraordinaria de personas  migrantes una medida de responsabilidad pol\\u00edtica, \\u00e9tica y social\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/mobilidad-humana\\\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\\\/#listItem\",\"position\":3,\"name\":\"Entidades de Iglesia consideran la regularizaci\\u00f3n extraordinaria de personas  migrantes una medida de responsabilidad pol\\u00edtica, \\u00e9tica y social\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/mobilidad-humana\\\/#listItem\",\"name\":\"Mobilidad Humana\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/#organization\",\"name\":\"Blog de C\\u00e1ritas Barcelona\",\"url\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/\",\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/caritasbcn\",\"https:\\\/\\\/www.instagram.com\\\/caritasbcn\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/caritasbcn\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/c\\u00e0ritas-barcelona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/author\\\/gestorwebcaritas17\\\/#author\",\"url\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/author\\\/gestorwebcaritas17\\\/\",\"name\":\"C\\u00e0ritas Diocesana de Barcelona\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/mobilidad-humana\\\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\\\/#webpage\",\"url\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/mobilidad-humana\\\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\\\/\",\"name\":\"Entidades de Iglesia consideran la regularizaci\\u00f3n extraordinaria de personas migrantes una medida de responsabilidad pol\\u00edtica, \\u00e9tica y social | Blog de C\\u00e1ritas Barcelona\",\"description\":\"Piden a la Administraci\\u00f3n que ofrezca posibilidades de registro presencial de expedientes a todas las personas extranjeras potencialmente beneficiarias La Red de Entidades para el Desarrollo Solidario (REDES), la Conferencia Espa\\u00f1ola de Religiosos (CONFER), C\\u00e1ritas y el Departamento de Migraciones de la Conferencia Episcopal Espa\\u00f1ola consideran que la aprobaci\\u00f3n del Real Decreto, que permitir\\u00e1 una regularizaci\\u00f3n extraordinaria de personas migrantes, es\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/mobilidad-humana\\\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/author\\\/gestorwebcaritas17\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/author\\\/gestorwebcaritas17\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.caritas.barcelona\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/04\\\/Ismael-centroFormacion-4-Caritas-Espanola-scaled-1.jpg\",\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/mobilidad-humana\\\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\\\/#mainImage\",\"width\":2560,\"height\":1920},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/mobilidad-humana\\\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\\\/#mainImage\"},\"datePublished\":\"2026-04-14T16:42:18+02:00\",\"dateModified\":\"2026-05-21T15:45:28+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/\",\"name\":\"Blog de C\\u00e1ritas Barcelona\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.caritas.barcelona\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Entidades de Iglesia consideran la regularizaci\u00f3n extraordinaria de personas migrantes una medida de responsabilidad pol\u00edtica, \u00e9tica y social | Blog de C\u00e1ritas Barcelona","description":"Piden a la Administraci\u00f3n que ofrezca posibilidades de registro presencial de expedientes a todas las personas extranjeras potencialmente beneficiarias La Red de Entidades para el Desarrollo Solidario (REDES), la Conferencia Espa\u00f1ola de Religiosos (CONFER), C\u00e1ritas y el Departamento de Migraciones de la Conferencia Episcopal Espa\u00f1ola consideran que la aprobaci\u00f3n del Real Decreto, que permitir\u00e1 una regularizaci\u00f3n extraordinaria de personas migrantes, es","canonical_url":"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"mobilidad humana","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\/#blogposting","name":"Entidades de Iglesia consideran la regularizaci\u00f3n extraordinaria de personas migrantes una medida de responsabilidad pol\u00edtica, \u00e9tica y social | Blog de C\u00e1ritas Barcelona","headline":"Entidades de Iglesia consideran la regularizaci\u00f3n extraordinaria de personas  migrantes una medida de responsabilidad pol\u00edtica, \u00e9tica y social","author":{"@id":"https:\/\/blog.caritas.barcelona\/es\/author\/gestorwebcaritas17\/#author"},"publisher":{"@id":"https:\/\/blog.caritas.barcelona\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/blog.caritas.barcelona\/wp-content\/uploads\/sites\/2\/2026\/04\/Ismael-centroFormacion-4-Caritas-Espanola-scaled-1.jpg","width":2560,"height":1920},"datePublished":"2026-04-14T16:42:18+02:00","dateModified":"2026-05-21T15:45:28+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\/#webpage"},"isPartOf":{"@id":"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\/#webpage"},"articleSection":"Mobilidad Humana, Opcional, C\u00e1ritas Diocesana de Barcelona"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/blog.caritas.barcelona\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/blog.caritas.barcelona\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/#listItem","name":"Mobilidad Humana"}},{"@type":"ListItem","@id":"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/#listItem","position":2,"name":"Mobilidad Humana","item":"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\/#listItem","name":"Entidades de Iglesia consideran la regularizaci\u00f3n extraordinaria de personas  migrantes una medida de responsabilidad pol\u00edtica, \u00e9tica y social"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.caritas.barcelona\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\/#listItem","position":3,"name":"Entidades de Iglesia consideran la regularizaci\u00f3n extraordinaria de personas  migrantes una medida de responsabilidad pol\u00edtica, \u00e9tica y social","previousItem":{"@type":"ListItem","@id":"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/#listItem","name":"Mobilidad Humana"}}]},{"@type":"Organization","@id":"https:\/\/blog.caritas.barcelona\/es\/#organization","name":"Blog de C\u00e1ritas Barcelona","url":"https:\/\/blog.caritas.barcelona\/es\/","sameAs":["https:\/\/twitter.com\/caritasbcn","https:\/\/www.instagram.com\/caritasbcn\/","https:\/\/www.youtube.com\/user\/caritasbcn","https:\/\/www.linkedin.com\/company\/c\u00e0ritas-barcelona"]},{"@type":"Person","@id":"https:\/\/blog.caritas.barcelona\/es\/author\/gestorwebcaritas17\/#author","url":"https:\/\/blog.caritas.barcelona\/es\/author\/gestorwebcaritas17\/","name":"C\u00e0ritas Diocesana de Barcelona"},{"@type":"WebPage","@id":"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\/#webpage","url":"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\/","name":"Entidades de Iglesia consideran la regularizaci\u00f3n extraordinaria de personas migrantes una medida de responsabilidad pol\u00edtica, \u00e9tica y social | Blog de C\u00e1ritas Barcelona","description":"Piden a la Administraci\u00f3n que ofrezca posibilidades de registro presencial de expedientes a todas las personas extranjeras potencialmente beneficiarias La Red de Entidades para el Desarrollo Solidario (REDES), la Conferencia Espa\u00f1ola de Religiosos (CONFER), C\u00e1ritas y el Departamento de Migraciones de la Conferencia Episcopal Espa\u00f1ola consideran que la aprobaci\u00f3n del Real Decreto, que permitir\u00e1 una regularizaci\u00f3n extraordinaria de personas migrantes, es","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/blog.caritas.barcelona\/es\/#website"},"breadcrumb":{"@id":"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\/#breadcrumblist"},"author":{"@id":"https:\/\/blog.caritas.barcelona\/es\/author\/gestorwebcaritas17\/#author"},"creator":{"@id":"https:\/\/blog.caritas.barcelona\/es\/author\/gestorwebcaritas17\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/blog.caritas.barcelona\/wp-content\/uploads\/sites\/2\/2026\/04\/Ismael-centroFormacion-4-Caritas-Espanola-scaled-1.jpg","@id":"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\/#mainImage","width":2560,"height":1920},"primaryImageOfPage":{"@id":"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\/#mainImage"},"datePublished":"2026-04-14T16:42:18+02:00","dateModified":"2026-05-21T15:45:28+02:00"},{"@type":"WebSite","@id":"https:\/\/blog.caritas.barcelona\/es\/#website","url":"https:\/\/blog.caritas.barcelona\/es\/","name":"Blog de C\u00e1ritas Barcelona","inLanguage":"es-ES","publisher":{"@id":"https:\/\/blog.caritas.barcelona\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Blog de C\u00e1ritas Barcelona","og:type":"article","og:title":"Entidades de Iglesia consideran la regularizaci\u00f3n extraordinaria de personas migrantes una medida de responsabilidad pol\u00edtica, \u00e9tica y social | Blog de C\u00e1ritas Barcelona","og:description":"Piden a la Administraci\u00f3n que ofrezca posibilidades de registro presencial de expedientes a todas las personas extranjeras potencialmente beneficiarias La Red de Entidades para el Desarrollo Solidario (REDES), la Conferencia Espa\u00f1ola de Religiosos (CONFER), C\u00e1ritas y el Departamento de Migraciones de la Conferencia Episcopal Espa\u00f1ola consideran que la aprobaci\u00f3n del Real Decreto, que permitir\u00e1 una regularizaci\u00f3n extraordinaria de personas migrantes, es","og:url":"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\/","fb:admins":"100006058908787","og:image":"https:\/\/blog.caritas.barcelona\/wp-content\/uploads\/sites\/2\/2026\/04\/Ismael-centroFormacion-4-Caritas-Espanola-scaled-1.jpg","og:image:secure_url":"https:\/\/blog.caritas.barcelona\/wp-content\/uploads\/sites\/2\/2026\/04\/Ismael-centroFormacion-4-Caritas-Espanola-scaled-1.jpg","og:image:width":2560,"og:image:height":1920,"article:tag":["mobilidad humana"],"article:published_time":"2026-04-14T14:42:18+00:00","article:modified_time":"2026-05-21T13:45:28+00:00","article:publisher":"https:\/\/www.facebook.com\/caritasbarcelona\/","twitter:card":"summary_large_image","twitter:site":"@caritasbcn","twitter:title":"Entidades de Iglesia consideran la regularizaci\u00f3n extraordinaria de personas migrantes una medida de responsabilidad pol\u00edtica, \u00e9tica y social | Blog de C\u00e1ritas Barcelona","twitter:description":"Piden a la Administraci\u00f3n que ofrezca posibilidades de registro presencial de expedientes a todas las personas extranjeras potencialmente beneficiarias La Red de Entidades para el Desarrollo Solidario (REDES), la Conferencia Espa\u00f1ola de Religiosos (CONFER), C\u00e1ritas y el Departamento de Migraciones de la Conferencia Episcopal Espa\u00f1ola consideran que la aprobaci\u00f3n del Real Decreto, que permitir\u00e1 una regularizaci\u00f3n extraordinaria de personas migrantes, es","twitter:creator":"@caritasbcn","twitter:image":"https:\/\/blog.caritas.barcelona\/wp-content\/uploads\/sites\/2\/2026\/04\/Ismael-centroFormacion-4-Caritas-Espanola-scaled-1.jpg"},"aioseo_meta_data":{"post_id":"16224","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-04-14 13:52:40","updated":"2026-05-21 14:17:42","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.caritas.barcelona\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/\" title=\"Mobilidad Humana\">Mobilidad Humana<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEntidades de Iglesia consideran la regularizaci\u00f3n extraordinaria de personas  migrantes una medida de responsabilidad pol\u00edtica, \u00e9tica y social\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/blog.caritas.barcelona\/es\/"},{"label":"Mobilidad Humana","link":"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/"},{"label":"Entidades de Iglesia consideran la regularizaci\u00f3n extraordinaria de personas  migrantes una medida de responsabilidad pol\u00edtica, \u00e9tica y social","link":"https:\/\/blog.caritas.barcelona\/es\/mobilidad-humana\/entidades-de-iglesia-consideran-la-regularizacion-extraordinaria-de-personas-migrantes-una-medida-de-responsabilidad-politica-etica-y-social\/"}],"_links":{"self":[{"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/posts\/16224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/comments?post=16224"}],"version-history":[{"count":1,"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/posts\/16224\/revisions"}],"predecessor-version":[{"id":16225,"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/posts\/16224\/revisions\/16225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/media\/16220"}],"wp:attachment":[{"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/media?parent=16224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/categories?post=16224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/tags?post=16224"},{"taxonomy":"autor","embeddable":true,"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/autor?post=16224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}