{"id":12082,"date":"2022-07-07T12:15:10","date_gmt":"2022-07-07T10:15:10","guid":{"rendered":"https:\/\/blog.caritas.barcelona\/?p=12082"},"modified":"2022-09-09T10:25:40","modified_gmt":"2022-09-09T08:25:40","slug":"el-archivo-de-caritas-diocesana-de-barcelona-recibe-una-importante-donacion","status":"publish","type":"post","link":"https:\/\/blog.caritas.barcelona\/es\/institucional-es\/el-archivo-de-caritas-diocesana-de-barcelona-recibe-una-importante-donacion\/","title":{"rendered":"C\u00e1ritas Barcelona recibe documentaci\u00f3n del extinto &#8220;Centro de Promoci\u00f3n Social Ntra. Sra. del Port&#8221;"},"content":{"rendered":"<p><span style=\"font-weight: 400\">La donaci\u00f3n, efectuada por el Dr. Juli de Nadal, permitir\u00e1 favorecer la preservaci\u00f3n y divulgaci\u00f3n de documentaci\u00f3n sobre este centro social.\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12078 aligncenter\" src=\"https:\/\/blog.caritas.barcelona\/wp-content\/uploads\/sites\/2\/2022\/07\/20220620_ActeDonacioCentreSocialNtraSraDelPort_2-scaled-e1657188686228.jpg\" alt=\"\" width=\"768\" height=\"576\" \/><\/p>\n<p><span style=\"font-weight: 400\">El Archivo de C\u00e1ritas Diocesana de Barcelona es un espacio en el que se conserva un fondo documental sobre la historia de la instituci\u00f3n, que refleja las situaciones de pobreza y exclusi\u00f3n social de la poblaci\u00f3n catalana desde 1944 hasta la actualidad. El pasado 20 de junio de 2022, el Archivo recibi\u00f3 una important\u00edsima donaci\u00f3n por parte del Dr. Juli de Nadal Capar\u00e0, quien entreg\u00f3 la documentaci\u00f3n que su padre, el Dr. Joaqu\u00edn de Nadal Baixeras, recopil\u00f3 a lo largo de varias d\u00e9cadas de incansable trabajo, en el Dispensario del \u201cCentro de Promoci\u00f3n Social de Ntra. Sra. del Port\u201d, Centro Social adherido a C\u00e1ritas en 1959, a\u00f1o en que se aprobaron sus Estatutos.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La donaci\u00f3n de esta documentaci\u00f3n es una pieza de gran valor para la serie documental de Centros Sociales (1958-1983), que actualmente se conserva en el Archivo de C\u00e1ritas, y que supone un testimonio hist\u00f3rico \u00fanico de un gran valor institucional e informativo. Entre los expedientes de esta serie, constan documentos que nos explican la vida de los Centros Sociales y de los barrios, y que exponen las graves deficiencias de la realidad de los suburbios de la \u00e9poca, traducida en el fen\u00f3meno del chabolismo y de los barrios con graves carencias urban\u00edsticas y sociales.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12080 aligncenter\" src=\"https:\/\/blog.caritas.barcelona\/wp-content\/uploads\/sites\/2\/2022\/07\/20220620_ActeDonacioCentreSocialNtraSraDelPort_4-e1657188718825.jpg\" alt=\"\" width=\"768\" height=\"576\" \/><\/p>\n<p><span style=\"font-weight: 400\">Los Centros Sociales eran espacios creados con el objetivo de convertirse en espacios representativos e impulsores de la vida social de los barrios, donde promocionar personal y comunitariamente a sus habitantes. Durante la d\u00e9cada de los sesenta, C\u00e1ritas se convirti\u00f3 en la principal instituci\u00f3n impulsora de estos centros, con el funcionamiento de m\u00e1s de una treintena de centros en la di\u00f3cesis de Barcelona.<\/span><\/p>\n<p><span style=\"font-weight: 400\">En estos centros se desarrollaban todo tipo de servicios (sanitarios, jur\u00eddicos, educativos, culturales, ben\u00e9ficos, asistenciales, laborales, participativos\u2026) y de actividades (revista, representaciones, charlas, exposiciones, cine, excursiones y colonias, deportivas\u2026), que se tradujeron en la creaci\u00f3n de espacios como guarder\u00edas, escuelas, dispensarios, comedores y cantinas, bibliotecas, cooperativas, mutuas, etc., y en el surgimiento de campa\u00f1as de concienciaci\u00f3n y denuncia con el fin de responder a las necesidades de los habitantes de los barrios.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La conservaci\u00f3n de la documentaci\u00f3n relacionada con estos Centros Sociales es una fuente de informaci\u00f3n de gran valor hist\u00f3rico, que desde el Archivo de C\u00e1ritas se trabaja por preservar. Por eso, desde C\u00e1ritas Diocesana de Barcelona queremos agradecer al Dr. Juli de Nadal su voluntad de realizar la donaci\u00f3n de esta interesante documentaci\u00f3n a nuestro Archivo, que nos permitir\u00e1 ampliar y continuar conservando la documentaci\u00f3n que tenemos de este Centro Social.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La donaci\u00f3n, efectuada por el Dr. Juli de Nadal, permitir\u00e1 favorecer la preservaci\u00f3n y divulgaci\u00f3n de documentaci\u00f3n sobre este centro social.\u00a0 El Archivo de C\u00e1ritas Diocesana de Barcelona es un espacio en el que se conserva un fondo documental sobre la historia de la instituci\u00f3n, que refleja las situaciones de pobreza y exclusi\u00f3n social de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":12078,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"autor":[2094],"class_list":["post-12082","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucional-es","autor-paula-gerboles-2"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/posts\/12082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/comments?post=12082"}],"version-history":[{"count":4,"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/posts\/12082\/revisions"}],"predecessor-version":[{"id":12217,"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/posts\/12082\/revisions\/12217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/media\/12078"}],"wp:attachment":[{"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/media?parent=12082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/categories?post=12082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/tags?post=12082"},{"taxonomy":"autor","embeddable":true,"href":"https:\/\/blog.caritas.barcelona\/es\/wp-json\/wp\/v2\/autor?post=12082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}